{"id":11010,"date":"2019-07-31T10:59:46","date_gmt":"2019-07-31T09:59:46","guid":{"rendered":"https:\/\/www.jour-de-peche.com\/?p=11010"},"modified":"2022-09-29T09:53:53","modified_gmt":"2022-09-29T08:53:53","slug":"peche-mouche-ariege-pyrenees-seche-et-nymphe","status":"publish","type":"post","link":"https:\/\/www.jour-de-peche.com\/es\/peche-mouche-ariege-pyrenees-seche-et-nymphe\/","title":{"rendered":"P\u00eache d&#8217;\u00e9t\u00e9&#8230;"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text el_class=\u00bbhauteurboite1&#8243;]<\/p>\n<h1>Stage de p\u00eache. P\u00eache \u00e0 la mouche. Apprendre \u00e0 p\u00eacher. Guide de p\u00eache. Ari\u00e8ge, 09. Aude, 11. Haute-Garonne, 31. Tarn, 81. P\u00eache en nymphe. P\u00eache en s\u00e8che. P\u00eache en nymphe au fil. P\u00eache \u00e0 l&#8217;espagnole. P\u00eache en tandem s\u00e8che nymphe. Perdigones. Occitanie. Phaesant Tail. Pyr\u00e9n\u00e9es.<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css_animation=\u00bbright-to-left\u00bb]<\/p>\n<h3><strong><em>Avec Corentin, Hubert, Vincent, et en solo&#8230;<br \/>\n<\/em><\/strong><\/h3>\n<p><em>Juillet 2019,<\/em><\/p>\n<p><em>Sur les rivi\u00e8res ari\u00e9geoises&#8230;<br \/>\n<\/em><\/p>\n<p>_ _ _ _ _ _ _ _ _ _ _ _ _[\/vc_column_text][vc_column_text]Quelques nouvelles de ces jours-ci&#8230;.<\/p>\n<p>D&#8217;abord, avec Matthieu (en stage de guide de p\u00eache) on recevait Corentin pour une session 100 % p\u00eache en s\u00e8che. Il avait clairement choisi sa journ\u00e9e, y&#8217;avait une vraie activit\u00e9 de surface ce jour-l\u00e0!<\/p>\n<p>Corentin a eu une belle facilit\u00e9 \u00e0 mettre en \u0153uvre une gestuelle efficace pour poser sa mouche. Le plus d\u00e9licat aura \u00e9t\u00e9 de travailler le ferrage&#8230;<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-01.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-11011\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-01-281x375.jpg\" alt=\"\" width=\"281\" height=\"375\" \/><\/a> <a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-02.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-11014\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-02-281x375.jpg\" alt=\"\" width=\"281\" height=\"375\" \/><\/a><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>Je recevais \u00e9galement Hubert pour une journ\u00e9e mixte de p\u00eache en s\u00e8che et en nymphe.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-03.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-11017\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-03-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>Et c&#8217;est une p\u00eache en tandem s\u00e8che-nymphe qui nous aura apport\u00e9 le plus de r\u00e9sultats, une chouette d\u00e9couverte pour Hubert.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-04.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11020\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-04-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>En mode solo, lors d&#8217;un petit rep\u00e9rage d&#8217;une paire d&#8217;heures, je me suis r\u00e9gal\u00e9 avec une p\u00eache l\u00e9g\u00e8re en nymphe.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-06.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11026\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-06-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>Les truites \u00e9taient positionn\u00e9es pour la plupart dans peu d&#8217;eau sur les bordures.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-07.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11029\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-07-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>Elles \u00e9taient clairement dehors&#8230;<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-08.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11032\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-08-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>Quelques unes \u00e9taient plac\u00e9es dans des veines plus profondes&#8230; mais beaucoup moins.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-09.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11035\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-09-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>Il fallait p\u00eacher l\u00e9ger, avec des nymphes sur billes en 2,4 mm et 2,8 mm dans les petites veines de bordures, parfois sous les arbres.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-16.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11056\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-16-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>L&#8217;une des constatations les plus fr\u00e9quentes que j&#8217;ai lors des stages de p\u00eache c&#8217;est l&#8217;\u00e9tonnement des p\u00eacheurs sur le placement des poissons.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11044\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-12-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>Ces p\u00eaches fines de petites et moyennes rivi\u00e8res sont un v\u00e9ritable r\u00e9gal&#8230;.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11047\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-13-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>Je n&#8217;ai pas eu le temps d&#8217;essayer en s\u00e8che-nymphe, car \u00e7a p\u00eachait tout simplement tr\u00e8s bien \u00e0 une ou deux nymphes.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-14.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11050\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-14-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>J&#8217;ai pris une douzaine de poissons, j&#8217;en d\u00e9croche un, et je casse au ferrage sur un autre. Ce secteur est valid\u00e9 pour d&#8217;autres sorties, en guidage ou pas!<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11053\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-15-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>Vincent, en vacances dans la r\u00e9gion, avait envie de p\u00eacher une rivi\u00e8re d&#8217;un autre gabarit!<\/p>\n<p>Il p\u00eache aussi bien les carnassiers que la truite, en France et \u00e0 l&#8217;\u00e9tranger.<\/p>\n<p>L&#8217;objectif du jour \u00e9tait de d\u00e9couvrir la p\u00eache \u00e0 la mouche en nymphe en grande rivi\u00e8re.<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-05.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11023\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-05-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>Je crois bien qu&#8217;il s&#8217;est r\u00e9gal\u00e9 \ud83d\ude42<\/p>\n<p>Et, dans ses moments de pose, j&#8217;ai eu le bonheur d&#8217;une chouette s\u00e9rie de poissons&#8230;<\/p>\n<p><a href=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-19.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11067\" src=\"https:\/\/www.jour-de-peche.com\/wp-content\/uploads\/2019\/07\/peche-mouche-ariege-19-281x375.jpg\" alt=\"\" width=\"281\" height=\"375\" \/><\/a><\/p>\n<p>[\/vc_column_text][vc_separator][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9149&#8243; img_size=\u00bbfull\u00bb style=\u00bbvc_box_shadow_3d\u00bb onclick=\u00bbcustom_link\u00bb img_link_target=\u00bb_blank\u00bb css_animation=\u00bbappear\u00bb link=\u00bbhttps:\/\/www.facebook.com\/steph.legentilhomme\u00bb title=\u00bbFacebook :\u00bb][vc_facebook][\/vc_column][vc_column width=\u00bb1\/2&#8243; css=\u00bb.vc_custom_1659036664809{padding-top: 30px !important;}\u00bb][vc_btn title=\u00bbInfos guidages\u00bb color=\u00bbviolet\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Fwww.jour-de-peche.com%2F\u00bb][vc_btn title=\u00bbLivre d&#8217;Or\u00bb color=\u00bbwarning\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Fwww.jour-de-peche.com%2Flivre-or-peche-irlande-et-france%2F\u00bb][vc_btn title=\u00bbCh\u00e8ques-cadeaux guidages\u00bb color=\u00bbsky\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Fwww.jour-de-peche.com%2Fcheque-cadeau-peche-carnassiers-et-truites%2F\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text el_class=\u00bbhauteurboite1&#8243;] Stage de p\u00eache. P\u00eache \u00e0 la mouche. Apprendre \u00e0 p\u00eacher. Guide de p\u00eache. Ari\u00e8ge, 09. Aude, 11. Haute-Garonne, 31. Tarn, 81. P\u00eache en nymphe. P\u00eache en s\u00e8che. P\u00eache [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[184,373,267,276,275,374,2],"tags":[86,97,85,145,157,45,277,58,305,303,9,352,78,80,304,56,215,375],"class_list":["post-11010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guidages-inititaions-mouche-fr-fr-fr","category-mouche","category-mouche-ariege-09","category-mouche-aude-11","category-mouche-tarn-81","category-technique","category-tous-les-recits-de-peche-fr","tag-apprendre-a-pecher","tag-ariege","tag-aude","tag-guide-de-peche","tag-haute-garonne","tag-mouche","tag-nymphe","tag-nymphe-au-fil","tag-occitanie","tag-pam","tag-peche","tag-peche-a-lespagnole","tag-peche-a-la-mouche","tag-peche-en-seche","tag-perdigones","tag-sejour-de-peche","tag-stage-de-peche","tag-tutoriel"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/posts\/11010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/comments?post=11010"}],"version-history":[{"count":8,"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/posts\/11010\/revisions"}],"predecessor-version":[{"id":533144,"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/posts\/11010\/revisions\/533144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/media\/11059"}],"wp:attachment":[{"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/media?parent=11010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/categories?post=11010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jour-de-peche.com\/es\/wp-json\/wp\/v2\/tags?post=11010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}